{"id":47657,"date":"2026-07-15T01:30:12","date_gmt":"2026-07-15T04:30:12","guid":{"rendered":"https:\/\/gilpimentel.com.br\/site\/?p=47657"},"modified":"2026-07-14T19:29:08","modified_gmt":"2026-07-14T22:29:08","slug":"decima-edicao-da-noite-dos-museus-tera-corrida-noturna-com-largada-as-23h59-em-porto-alegre","status":"publish","type":"post","link":"https:\/\/gilpimentel.com.br\/site\/decima-edicao-da-noite-dos-museus-tera-corrida-noturna-com-largada-as-23h59-em-porto-alegre\/","title":{"rendered":"D\u00c9CIMA EDI\u00c7\u00c3O DA NOITE DOS MUSEUS TER\u00c1 CORRIDA NOTURNA COM LARGADA \u00c0S 23H59 EM PORTO ALEGRE"},"content":{"rendered":"<p>Iniciativa que foi sucesso na edi\u00e7\u00e3o passada do Noite dos Museus, a corrida noturna promovida pelo projeto voltar\u00e1 a ocupar as ruas da cidade neste ano, trazendo novidades. Dessa vez, a Noite Run ser\u00e1 realizada com largada \u00e0s 23h59 do dia 28 de novembro para que os competidores tamb\u00e9m possam aproveitar a visita\u00e7\u00e3o aos espa\u00e7os culturais das 18h at\u00e9 a meia-noite. Al\u00e9m de conferir os museus iluminados durante o percurso, os participantes ainda ser\u00e3o surpreendidos com interven\u00e7\u00f5es ao longo do trajeto.<\/p>\n<p>Assim como na edi\u00e7\u00e3o passada, a prova ter\u00e1 largada na Av. Borges de Medeiros, esquina com a Rua Sete de Setembro, e percorrer\u00e1 o Centro Hist\u00f3rico, passando por edif\u00edcios hist\u00f3ricos, pra\u00e7as e monumentos importantes da capital. A expectativa \u00e9 que cerca de 5 mil participantes tomem as ruas, em percursos de 4 km e 8 km que podem ser conclu\u00eddos em at\u00e9 80 minutos.<\/p>\n<p>A largada ser\u00e1 justamente em um dos principais pontos do evento, tendo de um lado o ic\u00f4nico Mercado P\u00fablico e, do outro, a Pra\u00e7a Montevid\u00e9u, em frente ao Museu de Arte do Pa\u00e7o (MAPA). O trajeto ainda inclui passagens por pontos tur\u00edsticos como a Usina do Gas\u00f4metro e a R\u00f3tula das Cuias, onde est\u00e1 instalada a Supercuia.<\/p>\n<p>Outro destaque desta edi\u00e7\u00e3o \u00e9 que as camisetas e as medalhas da corrida est\u00e3o sendo desenvolvidas pela equipe da Ag\u00eancia Escala, em parceria com Bruno Schilling, artista visual, muralista e designer nascido em Novo Hamburgo, que tem se destacado por projetos que transitam entre a arte urbana, o design e a arquitetura. O kit da edi\u00e7\u00e3o passada praticamente se transformou em item de cole\u00e7\u00e3o entre os corredores de rua, e a proposta \u00e9 repetir esse sucesso em um ano que marca tamb\u00e9m a chegada da d\u00e9cima edi\u00e7\u00e3o do Noite dos Museus.<\/p>\n<p>A corrida segue as regras da World Athletics e da Confedera\u00e7\u00e3o Brasileira de Atletismo (CBAt), e ser\u00e1 disputada nas categorias masculina e feminina. Para participar do percurso de 4km \u00e9 necess\u00e1rio ter no m\u00ednimo 14 anos e, para o de 8km, no m\u00ednimo 16 anos completos at\u00e9 o dia da prova. Menores de 18 anos s\u00f3 podem participar com autoriza\u00e7\u00e3o de um respons\u00e1vel legal.<\/p>\n<p>As inscri\u00e7\u00f5es j\u00e1 est\u00e3o abertas em www.nexteventosbrasil.com com pre\u00e7os a partir de R$ 130, no primeiro lote. No site, tamb\u00e9m \u00e9 poss\u00edvel conferir o regulamento completo e visualizar os percursos.<\/p>\n<p>Sobre o evento comemorativo de 10 anos do Noite dos Museus<\/p>\n<p>O Noite dos Museus nasceu em 2016 para aproximar o p\u00fablico das institui\u00e7\u00f5es culturais de Porto Alegre e incentivar a visita \u00e0s exposi\u00e7\u00f5es e aos espa\u00e7os de arte. Desde ent\u00e3o, o projeto realiza eventos anuais na capital ga\u00facha, com p\u00fablico crescente a cada evento. Somente em 2025, a iniciativa reuniu mais de 250 mil pessoas, ultrapassando a marca de 1 milh\u00e3o de participantes nos \u00faltimos nove anos.<\/p>\n<p>Em 2026, o projeto prepara mais uma noite especial, desta vez para celebrar sua primeira d\u00e9cada. A edi\u00e7\u00e3o comemorativa refor\u00e7a a ess\u00eancia do evento, que foi criado para tornar a arte acess\u00edvel a milhares de pessoas. Sob o tema \u201cDerrubando Muros \u2013 Construindo acessos\u201c, a d\u00e9cima Noite dos Museus lembra que o evento derruba as barreiras que podem afastar as pessoas de espa\u00e7os que deveriam ser de todos, sejam elas sociais, culturais ou financeiras.<\/p>\n<p>Ser\u00e3o diversos espa\u00e7os culturais abertos para visita\u00e7\u00e3o no dia 28 de novembro, das 18h at\u00e9 a meia-noite, e dezenas de apresenta\u00e7\u00f5es art\u00edsticas realizadas dentro das institui\u00e7\u00f5es e em diferentes palcos espalhados pela cidade, tudo gratuitamente. A programa\u00e7\u00e3o completa ser\u00e1 anunciada em breve.<\/p>\n<p>O Noite dos Museus 2026 conta com financiamento via Lei Rouanet \u2013 Incentivo a Projetos Culturais e via Lei de Incentivo \u00e0 Cultura, planejamento e produ\u00e7\u00e3o da Rompecabezas e realiza\u00e7\u00e3o do Instituto Noite dos Museus e do Minist\u00e9rio da Cultura.<\/p>\n<p>SERVI\u00c7O<\/p>\n<p>Noite Run<\/p>\n<p>Dia 28 de novembro, s\u00e1bado<\/p>\n<p>Largada \u00e0s 23h59 na Av. Borges de Medeiros, esquina com a Rua Sete de Setembro<\/p>\n<p>Encerramento \u00e0s 01h30 do dia 29 de novembro, com evento de premia\u00e7\u00e3o na Pra\u00e7a da Alf\u00e2ndega<\/p>\n<p>Inscri\u00e7\u00f5es pelo site www.nexteventosbrasil.com, onde tamb\u00e9m \u00e9 poss\u00edvel conferir o regulamento completo<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciativa que foi sucesso na edi\u00e7\u00e3o passada do Noite dos Museus, a corrida noturna promovida pelo projeto voltar\u00e1 a ocupar as ruas da cidade neste &hellip; <\/p>\n","protected":false},"author":2,"featured_media":47658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-47657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","latest_post"],"_links":{"self":[{"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/posts\/47657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/comments?post=47657"}],"version-history":[{"count":1,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/posts\/47657\/revisions"}],"predecessor-version":[{"id":47659,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/posts\/47657\/revisions\/47659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/media\/47658"}],"wp:attachment":[{"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/media?parent=47657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/categories?post=47657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gilpimentel.com.br\/site\/wp-json\/wp\/v2\/tags?post=47657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}